{"id":28304,"date":"2019-12-23T12:03:39","date_gmt":"2019-12-23T11:03:39","guid":{"rendered":"https:\/\/www.wildsuits.eu\/?p=28304"},"modified":"2023-04-20T10:31:10","modified_gmt":"2023-04-20T08:31:10","slug":"wildsuits-combinaisons-surf-limestone-neoprene","status":"publish","type":"post","link":"https:\/\/wildsuits.eu\/pt\/wildsuits-combinaisons-surf-limestone-neoprene\/","title":{"rendered":"Wildsuits, des combinaisons de surf en limestone"},"content":{"rendered":"<h1 class=\"wp-block-heading\">Wildsuits, des combinaisons de surf en limestone !<\/h1>\n\n\n\n<p>Ta conscience de surfeur te pousse \u00e0 questionner le mat\u00e9riel pas toujours \u00e9cologique que tu utilises pour surfer ? Bienvenue au club ! Cette question a d\u2019ailleurs donn\u00e9 vie \u00e0 Wildsuits, en fabriquant des combinaisons en <strong>n\u00e9opr\u00e8ne limestone<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Et c\u2019est quoi le limestone ? Litt\u00e9ralement, limestone signifie \u201croche calcaire\u201d. Tu l\u2019auras compris, c\u2019est une combinaison faite \u00e0 base de roche calcaire. C\u2019est une soci\u00e9t\u00e9 japonaise qui a mis au point ce mat\u00e9riau, permettant d\u2019obtenir un n\u00e9opr\u00e8ne non issu de la p\u00e9trochimie. Un pas de plus vers une mer plus bleue et un ciel plus clair !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>UNE COMBINAISON DE SURF VERTE&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\" translation-block\">Non tu n\u2019as pas de probl\u00e8me de vue, les combinaisons Wildsuits sont bien noires mais d\u00e9finitivement plus eco-friendly<strong>.<\/strong>&nbsp;Parce que nous voulons ce qu\u2019il y a de meilleur, nous avons choisi le plus haut de gamme des n\u00e9opr\u00e8nes limestone&nbsp; !<\/p>\n\n\n\n<p>Nos combis de surf poss\u00e8de un n\u00e9opr\u00e8ne compos\u00e9 \u00e0 70% de roche calcaire et \u00e0 30% de pneus recycl\u00e9s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LA ROCHE CALCAIRE :\u00a0<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-1024x768.jpg\" alt=\"Calcaire\/limestone Wildsuits\" class=\"wp-image-40538\" srcset=\"https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-1024x768.jpg 1024w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-300x225.jpg 300w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-768x576.jpg 768w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-1536x1152.jpg 1536w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-2048x1536.jpg 2048w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-16x12.jpg 16w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/02_Calcaire_Tech-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Il s\u2019agit d\u2019un mat\u00e9riau naturel qui requiert un processus de transformation beaucoup plus respectueux de l\u2019environnement que le n\u00e9opr\u00e8ne classique. Ce dernier est issu de la p\u00e9trochimie, chose que l\u2019on veut \u00e9viter pour limiter l\u2019impact environnemental de Wildsuits.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ECO CARBON BLACK :<\/h3>\n\n\n\n<p>Le carbon black est issu de la transformation de pneus recycl\u00e9s. Ce n\u2019est autre que le deuxi\u00e8me ingr\u00e9dient de notre ne\u00f3pr\u00e8ne. Cela rend nos combinaisons de surf plus r\u00e9sistantes dans le temps, face \u00e0 l\u2019exposition au soleil tout comme \u00e0 leur utilisation. Dor\u00e9navant cet ingr\u00e9dient est donc issu de produits recycl\u00e9s. Sachant que cette derni\u00e8re est \u00e9galement compos\u00e9 de bouteille en plastique recycl\u00e9es. Une grande avanc\u00e9e dans le milieu de la combinaison de surf ! La production de nos combis limestone engendre 72% d\u2019\u00e9missions de CO2 en moins qu\u2019une combinaison classique. Seulement 200g par produit !\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-1024x768.jpg\" alt=\"Pneu Wildsuits\" class=\"wp-image-40539\" srcset=\"https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-1024x768.jpg 1024w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-300x225.jpg 300w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-768x576.jpg 768w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-1536x1152.jpg 1536w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-2048x1536.jpg 2048w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-16x12.jpg 16w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/01_Pneus_Tech-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En plus de cela, notre fournisseur s\u2019engage \u00e0 recycler les chutes de n\u00e9opr\u00e8ne lors de la d\u00e9coupe des pi\u00e8ces. Cette vision \u00e9co-responsable est un crit\u00e8re qui nous tient \u00e0 coeur dans la s\u00e9lection de nos partenaires.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Une combinaison plus performante<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"795\" height=\"1024\" src=\"https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-795x1024.jpg\" alt=\"La combinaison \u00e9co-responsable Wildsuits dans les mains d'un de nos riders\" class=\"wp-image-40574\" srcset=\"https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-795x1024.jpg 795w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-233x300.jpg 233w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-768x989.jpg 768w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-1193x1536.jpg 1193w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-1590x2048.jpg 1590w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-9x12.jpg 9w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-600x773.jpg 600w, https:\/\/wildsuits.eu\/wp-content\/uploads\/2023\/01\/Youri2-scaled.jpg 1988w\" sizes=\"(max-width: 795px) 100vw, 795px\" \/><figcaption class=\"wp-element-caption\">La combinaison eco-friendly<\/figcaption><\/figure>\n\n\n\n<p>Le limestone est \u00e9galement imperm\u00e9able \u00e0 98 %, soit quasiment 30% de plus qu\u2019une combi compos\u00e9e d\u2019un n\u00e9opr\u00e8ne classique.&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">La combinaison limestone est :&nbsp;<\/h5>\n\n\n\n<ul>\n<li class=\" translation-block\"><strong>Plus chaude<\/strong> : moins d\u2019infiltrations dans la combinaison signifie \u00e9galement une temp\u00e9rature \u00e0 l\u2019int\u00e9rieur des combinaisons Wildsuits plus stable et plus \u00e9lev\u00e9e dans la dur\u00e9e.<\/li>\n\n\n\n<li class=\" translation-block\"><strong>Plus l\u00e9g\u00e8re<\/strong> : en plus du poids du mat\u00e9riau qui de base est plus l\u00e9ger, si moins d\u2019eau est absorb\u00e9e par le n\u00e9opr\u00e8ne, c\u2019est \u00e9galement moins de poids \u00e0 porter. Tu te sentiras plus l\u00e9ger et plus libre dans tes mouvements.<\/li>\n\n\n\n<li class=\" translation-block\"><strong>Plus flexible<\/strong> : il s\u2019agit d\u2019une mati\u00e8re qui offre une souplesse sup\u00e9rieure \u00e0 celle du n\u00e9opr\u00e8ne classique tout en conservant une excellente solidit\u00e9. Tu n\u2019auras plus \u00e0 choisir entre une combinaison souple, mais fragile ou robuste, mais trop rigide. Probl\u00e8me r\u00e9solu !<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un prix raisonnable<\/strong><\/h2>\n\n\n\n<p>Nos combinaisons de surf limestone se comptent parmi les produits haut de gamme et poss\u00e8dent un co\u00fbt \u00e9lev\u00e9 de production. Cependant, nous ne voulons pas r\u00e9percuter le co\u00fbt d\u2019une combi plus qualitatif et \u00e9co-responsable sur le portefeuille de nos clients.&nbsp;<\/p>\n\n\n\n<p class=\" translation-block\">Notre solution ? Adopter une distribution tr\u00e8s s\u00e9lective de revendeurs. D\u2019ailleurs, n\u2019h\u00e9site pas \u00e0 consulter la liste de <a href=\"https:\/\/www.wildsuits.eu\/nos-shops\/\" target=\"_blank\" rel=\"noopener\"><strong>nos surf shops partenaires<\/strong><\/a>. Nous mettons \u00e9galement en vente nos produits sur notre site internet, dans <strong><a href=\"https:\/\/wildsuits-europe.com\/\" target=\"_blank\" rel=\"noopener\">notre boutique en ligne<\/a>,<\/strong> afin de contr\u00f4ler la distribution.<\/p>\n\n\n\n<p>Notre but est tout simplement d\u2019adopter un circuit de distribution court, avec le moins d\u2019interm\u00e9diaires possible. Le r\u00e9sultat est une s\u00e9lection de combinaisons de surf en limestone disponibles en <a href=\"https:\/\/wildsuits-europe.com\/collections\/wetsuits-combinaisons\/products\/3-2mm\" target=\"_blank\" rel=\"noopener\"><strong>3\/2mm<\/strong><\/a>, <strong><a href=\"https:\/\/wildsuits-europe.com\/collections\/wetsuits-combinaisons\/products\/4-3mm\" target=\"_blank\" rel=\"noopener\">4\/3mm<\/a> <\/strong>et <a href=\"https:\/\/wildsuits-europe.com\/collections\/wetsuits-combinaisons\/products\/5-4mm\" target=\"_blank\" rel=\"noopener\"><strong>5\/4mm<\/strong><\/a>&nbsp;\u00e0 un prix tr\u00e8s raisonnable.<\/p>\n\n\n\n<p>Fais de ton achat un vote et investi sur le futur avec nous. Rendons nos oc\u00e9ans plus propres.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ta conscience de surfeur te pousse \u00e0 questionner le mat\u00e9riel pas toujours \u00e9cologique que tu utilises pour surfer ?<\/p>","protected":false},"author":2,"featured_media":37500,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"_links":{"self":[{"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/posts\/28304"}],"collection":[{"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/comments?post=28304"}],"version-history":[{"count":5,"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/posts\/28304\/revisions"}],"predecessor-version":[{"id":40988,"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/posts\/28304\/revisions\/40988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/media\/37500"}],"wp:attachment":[{"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/media?parent=28304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/categories?post=28304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wildsuits.eu\/pt\/wp-json\/wp\/v2\/tags?post=28304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}